{"id":123,"date":"2018-10-23T15:08:00","date_gmt":"2018-10-23T13:08:00","guid":{"rendered":"http:\/\/posaunenchor-shg.de\/?p=123"},"modified":"2019-12-30T15:09:56","modified_gmt":"2019-12-30T14:09:56","slug":"meerbrass-begeisterte-in-der-marienkirche-von-wolfenbuettel","status":"publish","type":"post","link":"https:\/\/posaunenchor-shg.de\/index.php\/2018\/10\/23\/meerbrass-begeisterte-in-der-marienkirche-von-wolfenbuettel\/","title":{"rendered":"\u201eMeerBrass\u201c begeisterte in der Marienkirche von Wolfenb\u00fcttel"},"content":{"rendered":"\n<p>Der Posaunenchor \u201eMeerBrass\u201c veranstaltet  seit \u00fcber 20 Jahren regelm\u00e4\u00dfig eine \u00dcbungsfreizeit an unterschiedlichen  Orten in Deutschland. Von Spiekeroog bis Dresden und von Schwerte bis  R\u00fcgen haben die Schaumburger Bl\u00e4serinnen und Bl\u00e4ser schon in  verschiedenen Bundesl\u00e4ndern eine Freizeit mit abschlie\u00dfendem  Gottesdienstkonzert absolviert. In diesem Jahr war die historische Stadt  Wolfenb\u00fcttel mit ihrer beeindruckenden Hauptkirche Beatae Maria  Virginis (Marienkirche) das Ziel der dreit\u00e4gigen Reise. Geprobt wurde in  der Villa Seeliger der Landesmusikakademie &nbsp;Wolfenb\u00fcttel f\u00fcr den gro\u00dfen  Jubil\u00e4umsgottesdienst am Reformationstag um 15 Uhr in Sachsenhagen.  Anlass f\u00fcr das Jubil\u00e4um ist das 20-j\u00e4hrige gemeinsame Musizieren der  Posaunench\u00f6re Sachsenhagen und Hagenburg als gemeinsamer Posaunenchor  \u201eMeerBrass\u201c. Neben einer intensiven Stadtf\u00fchrung durch die Lessingstadt  Wolfenb\u00fcttel von \u201eKlein-Venedig\u201c bis zur Herzog August Bibliothek wurde  am Sonntag der Gottesdienst in der Marienkirche unter der Leitung von  Andreas Meyer musikalisch gestaltet. Au\u00dfer einer Fantasie, \u201eCalon L\u00e2n\u201c  (einer Hymne aus Wales) und \u201eGabriellas Song\u201c spielte der Bl\u00e4serchor  auch einen Satz vom Wolfenb\u00fctteler Komponisten Michael Praetorius, der  in der Marienkirche im 17. Jahrhundert unter der Orgel beigesetzt wurde.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/posaunenchor-shg.de\/wp-content\/uploads\/2019\/12\/MeerBrass-in-Wolfenb\u00fcttel-1024x665.jpg\" alt=\"\" class=\"wp-image-124\" width=\"768\" height=\"499\" srcset=\"https:\/\/posaunenchor-shg.de\/wp-content\/uploads\/2019\/12\/MeerBrass-in-Wolfenb\u00fcttel-1024x665.jpg 1024w, https:\/\/posaunenchor-shg.de\/wp-content\/uploads\/2019\/12\/MeerBrass-in-Wolfenb\u00fcttel-300x195.jpg 300w, https:\/\/posaunenchor-shg.de\/wp-content\/uploads\/2019\/12\/MeerBrass-in-Wolfenb\u00fcttel-768x499.jpg 768w, https:\/\/posaunenchor-shg.de\/wp-content\/uploads\/2019\/12\/MeerBrass-in-Wolfenb\u00fcttel-1536x998.jpg 1536w, https:\/\/posaunenchor-shg.de\/wp-content\/uploads\/2019\/12\/MeerBrass-in-Wolfenb\u00fcttel-2048x1331.jpg 2048w, https:\/\/posaunenchor-shg.de\/wp-content\/uploads\/2019\/12\/MeerBrass-in-Wolfenb\u00fcttel-1200x780.jpg 1200w, https:\/\/posaunenchor-shg.de\/wp-content\/uploads\/2019\/12\/MeerBrass-in-Wolfenb\u00fcttel-1980x1286.jpg 1980w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Der Posaunenchor \u201eMeerBrass\u201c veranstaltet seit \u00fcber 20 Jahren regelm\u00e4\u00dfig eine \u00dcbungsfreizeit an unterschiedlichen Orten in Deutschland. Von Spiekeroog bis Dresden und von Schwerte bis R\u00fcgen haben die Schaumburger Bl\u00e4serinnen und Bl\u00e4ser schon in verschiedenen Bundesl\u00e4ndern eine Freizeit mit abschlie\u00dfendem Gottesdienstkonzert absolviert. In diesem Jahr war die historische Stadt Wolfenb\u00fcttel mit ihrer beeindruckenden Hauptkirche Beatae Maria [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-123","post","type-post","status-publish","format-standard","hentry","category-6"],"_links":{"self":[{"href":"https:\/\/posaunenchor-shg.de\/index.php\/wp-json\/wp\/v2\/posts\/123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/posaunenchor-shg.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/posaunenchor-shg.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/posaunenchor-shg.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/posaunenchor-shg.de\/index.php\/wp-json\/wp\/v2\/comments?post=123"}],"version-history":[{"count":2,"href":"https:\/\/posaunenchor-shg.de\/index.php\/wp-json\/wp\/v2\/posts\/123\/revisions"}],"predecessor-version":[{"id":126,"href":"https:\/\/posaunenchor-shg.de\/index.php\/wp-json\/wp\/v2\/posts\/123\/revisions\/126"}],"wp:attachment":[{"href":"https:\/\/posaunenchor-shg.de\/index.php\/wp-json\/wp\/v2\/media?parent=123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/posaunenchor-shg.de\/index.php\/wp-json\/wp\/v2\/categories?post=123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/posaunenchor-shg.de\/index.php\/wp-json\/wp\/v2\/tags?post=123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}