{"id":310,"date":"2009-07-04T17:40:00","date_gmt":"2009-07-04T15:40:00","guid":{"rendered":"http:\/\/posaunenchor-shg.de\/?p=310"},"modified":"2020-01-04T17:45:23","modified_gmt":"2020-01-04T16:45:23","slug":"jungblaesertreffen-am-11-12-september-2009-in-hagenburg","status":"publish","type":"post","link":"https:\/\/posaunenchor-shg.de\/index.php\/2009\/07\/04\/jungblaesertreffen-am-11-12-september-2009-in-hagenburg\/","title":{"rendered":"Jungbl\u00e4sertreffen am 11. &#038; 12. September 2009 in Hagenburg"},"content":{"rendered":"\n<p>Das Jungbl\u00e4sertreffen im Rahmen des \nLandesposaunenfestes 2009 in Gro\u00dfenheidorn am Freitag, den 11. September\n bis Samstag, den 12. September 2009 soll ganz im Zeichen des\nAustausches und Kennenlernens von Jungbl\u00e4sern aus Schaumburg-Lippe \nstehen.<br><br>\nFreitag, 07.08.\u00b409<br>\n18 bis 20 Uhr vorbereitende Probe aller Jungbl\u00e4ser (Nicolai-Kirche Hagenburg)<\/p>\n\n\n\n<p>\n\n\nFreitag, 11.09.\u00b409<br>\nAnreise ab 15 Uhr und Aufbau der mitgebrachten Zelte<br>\nGemeinsame Probe in der Nicolai-Kirche<br>\nGrillen mit Livemusik<br>\n\u00dcbernachtung in Zelten<br><br>\n\nSamstag, 12.09.\u00b409 <br>\nFr\u00fchst\u00fcck<br>\n\u201eWarm up\u201c mit Instrumenten<br>\nSchifffahrt nach Steinhude mit Platzkonzert<br>\nMittagessen in Hagenburg<br>\nSpa\u00df und Spiel<br>\nProben f\u00fcr das Abschlusskonzert<br>\n19 Uhr Abschlusskonzert<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/posaunenchor-shg.de\/wp-content\/uploads\/2020\/01\/Jungblaeser_2009_kl.jpg\" alt=\"\" class=\"wp-image-319\" width=\"690\" height=\"399\" srcset=\"https:\/\/posaunenchor-shg.de\/wp-content\/uploads\/2020\/01\/Jungblaeser_2009_kl.jpg 690w, https:\/\/posaunenchor-shg.de\/wp-content\/uploads\/2020\/01\/Jungblaeser_2009_kl-300x173.jpg 300w\" sizes=\"auto, (max-width: 690px) 100vw, 690px\" \/><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Das Jungbl\u00e4sertreffen im Rahmen des Landesposaunenfestes 2009 in Gro\u00dfenheidorn am Freitag, den 11. September bis Samstag, den 12. September 2009 soll ganz im Zeichen des Austausches und Kennenlernens von Jungbl\u00e4sern aus Schaumburg-Lippe stehen. Freitag, 07.08.\u00b409 18 bis 20 Uhr vorbereitende Probe aller Jungbl\u00e4ser (Nicolai-Kirche Hagenburg) Freitag, 11.09.\u00b409 Anreise ab 15 Uhr und Aufbau der mitgebrachten [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-310","post","type-post","status-publish","format-standard","hentry","category-16"],"_links":{"self":[{"href":"https:\/\/posaunenchor-shg.de\/index.php\/wp-json\/wp\/v2\/posts\/310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/posaunenchor-shg.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/posaunenchor-shg.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/posaunenchor-shg.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/posaunenchor-shg.de\/index.php\/wp-json\/wp\/v2\/comments?post=310"}],"version-history":[{"count":2,"href":"https:\/\/posaunenchor-shg.de\/index.php\/wp-json\/wp\/v2\/posts\/310\/revisions"}],"predecessor-version":[{"id":320,"href":"https:\/\/posaunenchor-shg.de\/index.php\/wp-json\/wp\/v2\/posts\/310\/revisions\/320"}],"wp:attachment":[{"href":"https:\/\/posaunenchor-shg.de\/index.php\/wp-json\/wp\/v2\/media?parent=310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/posaunenchor-shg.de\/index.php\/wp-json\/wp\/v2\/categories?post=310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/posaunenchor-shg.de\/index.php\/wp-json\/wp\/v2\/tags?post=310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}